{"id":3041,"date":"2018-11-27T06:12:29","date_gmt":"2018-11-27T06:12:29","guid":{"rendered":"https:\/\/www.apdha.org\/cadiz\/?p=3041"},"modified":"2018-11-27T06:12:29","modified_gmt":"2018-11-27T06:12:29","slug":"derechos-humanos-en-la-frontera-sur","status":"publish","type":"post","link":"https:\/\/www.apdha.org\/cadiz\/derechos-humanos-en-la-frontera-sur\/","title":{"rendered":"Derechos Humanos en la Frontera Sur"},"content":{"rendered":"<p><span style=\"color: #008080;\"><strong><a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado.jpg\"><img class=\"alignnone  wp-image-3042\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado.jpg\" alt=\"\" width=\"652\" height=\"202\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado.jpg 1920w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado-300x93.jpg 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado-768x238.jpg 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado-1024x317.jpg 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Ana-Rosado-150x46.jpg 150w\" sizes=\"(max-width: 652px) 100vw, 652px\" \/><\/a><\/strong><\/span><\/p>\n<p><span style=\"color: #008080;\"><strong>Ana Rosado <\/strong><\/span>pertenece al <strong>\u00c1rea de Migraciones de la APDHA<\/strong><\/p>\n<p>Dice el art\u00edculo 13 DUDH que \u201c<em>Toda persona tiene derecho a circular libremente y a elegir su residencia en el territorio de un Estado. Toda persona tiene derecho a salir de cualquier pa\u00eds, incluso del propio, y a regresar a su pa\u00eds<\/em>\u201d.<\/p>\n<p>Ser\u00eda conveniente que los Estados y quienes gobiernan, responsables y garantes del cumplimiento de estos derechos, definan claramente a quienes consideran personas y como tales sujetos susceptibles de este derecho universal.<\/p>\n<p>Al analizar <em>nuestra<\/em> frontera sur es lamentable comprobar que, para los Estados europeos, quienes no han nacido en un determinado territorio y no responden a un determinado perfil \u00e9tnico y nivel socioecon\u00f3mico no son consideradas personas de pleno derecho. De hecho, no hay m\u00e1s que hacer un recorrido por los \u00faltimos 20 a\u00f1os de pol\u00edticas migratorias (y concretamente este 2018) y escuchar sus discursos perversos e intencionados que legitiman estas pol\u00edticas migratorias.<\/p>\n<p><strong>Primero habr\u00eda que hacerlas ilegales<\/strong>. Nuestra ley de extranjer\u00eda establece una serie de requisitos para poder migrar de forma legal: s\u00f3lo son bienvenidas todas aquellas personas que sean \u201c\u00fatiles\u201d y \u201cnecesarias\u201d para nuestra econom\u00eda. Hablemos por ejemplo de los \u201ccontingentes\u201d, como las temporeras en los campos de Huelva o de c\u00f3mo lo intentaron<em> de forma legal y ordenada <\/em>Samuel y Veronique, perdiendo la vida en el Estrecho al hab\u00e9rseles denegado el visado -una autorizaci\u00f3n plasmada en un papel- por razones humanitarias.<\/p>\n<p><strong>Tambi\u00e9n criminalizarlas<\/strong>. Se establecen acuerdos con pa\u00edses de origen o tr\u00e1nsito que claramente vulneran los derechos humanos de forma sistem\u00e1tica. Estos acuerdos econ\u00f3micos se denominan \u201cacuerdos contra la inmigraci\u00f3n ilegal, terrorismo o tr\u00e1fico de armas\u201d o de forma c\u00ednica \u201ccooperaci\u00f3n de ayuda al desarrollo\u201d. En estos convenios se invierten grandes cantidades de dinero que se destinan a impedir el acceso a personas por un punto habilitado -aeropuertos, puestos fronterizos o puertos mar\u00edtimos-. En lugar para paliar la desigualdad y que de alguna forma se repare la deuda hist\u00f3rica con los pa\u00edses africanos tras siglos de expolio y explotaci\u00f3n de sus recursos naturales, las \u201cayudas\u201d de esta \u201ccooperaci\u00f3n\u201d van destinadas a encerrar a los migrantes en macro prisiones, a realizar grandes redadas en las viviendas o campamentos donde malviven o a ejecutar traslados masivos utilizando la violencia m\u00e1s cruel.<\/p>\n<p><strong>Luego etiquetarles de violentos<\/strong>. Les impiden el acceso por puntos habilitados y se levantan muros y vallas con todo tipo de artilugios y cuchillas. Legalizan pr\u00e1cticas ilegales, condenadas por el Tribunal Europeo de Derechos Humanos, y que sean otros u otras las que \u201casuman\u201d el <em>cuerpo a cuerpo<\/em> para \u201cprotegernos\u201d de las <em>no<\/em> personas. Como Nana Roger Chimi, Larios Fotio, Ousman Kenzo, Armand Ferdinand Souop, Daouda Dakole, Blaise Fotchin, Oumar Ben Sandra, Jeannot Flame, Yves Martin Bilong, Keita Ibrahim, Youssouf, Bikai Luc firmin y Samba. 14 personas que perdieron la vida el 4 de febrero de 2014 en la frontera de El Tarajal, Ceuta.<\/p>\n<p><strong>Pero a\u00fan as\u00ed siguen viniendo<\/strong>. Entonces habr\u00e1 que tratarlos como una amenaza. Se les presentar\u00e1 como una \u00a0oleada, una invasi\u00f3n\u2026 como una masa descomunal en la que se mezclan buenos y malos: aquellos que huyen de la barbarie y que buscan la protecci\u00f3n de occidente o aquellos que suponen un peligro para nuestra seguridad, econom\u00eda y nuestros valores culturales y sociales. Pero sobre todo se les presenta como unos desalmados -adem\u00e1s de delincuentes organizados- que se enriquecen a costa del sufrimiento de sus propios <em>hermanos y hermanas<\/em>, porque les cobran un m\u00ednimo de 25 veces m\u00e1s de lo que cuesta un billete de ferry meti\u00e9ndolos en juguetes infantiles.<\/p>\n<p>Y habr\u00e1 que despojarles de toda dignidad haci\u00e9ndoles dormir a la intemperie en las cubiertas de los barcos de salvamento, hacinadas o sin mantas limpias y con ropas mojadas, separando a las familias\u2026 con la excusa de que adem\u00e1s \u201cconsumen\u201d recursos institucionales que pagamos con impuestos las <em>si <\/em>personas.<\/p>\n<p><strong>Y no hacer nada, invisibiliz\u00e1ndolas y vulnerabiliz\u00e1ndolas<\/strong>. En el estado espa\u00f1ol no existe un sistema de acogida: \u00a0se les detiene, identifica y expulsa violando en la mayor\u00eda de las ocasiones la legislaci\u00f3n internacional. No se \u00a0garantiza la asistencia jur\u00eddica ni la traducci\u00f3n, se les retiene en c\u00e1rceles para extranjeros en condiciones infrahumanas como en el CIE de Algeciras, en prisiones como la Archidona que fue utilizada en 2017 para detener a 572 personas y que le cost\u00f3 la vida a Mohamed Bouderala, o en espacios no habilitados como casetas de feria, pabellones polideportivos o naves industriales. Todo ello sin haber cometido ning\u00fan delito y excediendo el tiempo legal permitido.<\/p>\n<p>O se las deja en la calle con una orden de expulsi\u00f3n o devoluci\u00f3n entre los dientes, con una mano delante y otra detr\u00e1s o se les expulsa en vuelos concertados con agencias europeas, como el que le cost\u00f3 la vida a Osamuyi Aikpitanyi en 2007. \u00a0Y todo por haber cometido una falta administrativa, la de no acceder a nuestro pa\u00eds por un punto habilitado.<\/p>\n<p>No son consideradas personas porque no tienen derecho a circular libremente y elegir su residencia en el territorio de un estado ya que se enfrentan a diario a la violencia que ejercen los Estados a trav\u00e9s de las identificaciones por perfil racial o redadas, como por ejemplo la que provoc\u00f3 la muerte a Mame Mbaye este 2018.<\/p>\n<p><strong>Entonces todas ellas no ser\u00e1n personas.<\/strong> Ser\u00e1n un cuerpo, un n\u00famero o una palabra en una l\u00e1pida. M\u00e1s de 8.000 personas han perdido la vida intentando llegar a Espa\u00f1a en 30 a\u00f1os en el Estrecho y el Mediterr\u00e1neo y otras miles m\u00e1s han perdido su vida en el camino.<\/p>\n<p>Un Estrecho, un Mediterr\u00e1neo y una Frontera Sur que son testigos de la desidia e inacci\u00f3n de nuestros gobernantes, del miedo, de la desesperaci\u00f3n, de la tragedia\u2026 pero tambi\u00e9n de los #Bozza, de la alegr\u00eda. Este 2018 ha sido testigo de la solidaridad y de la empat\u00eda de una ciudadan\u00eda y de algunas administraciones que <strong>si<\/strong> hemos asumido que todas las personas nacemos iguales en dignidad y derechos, y que esos cuerpos que nos <em>devuelve<\/em> el mar, son personas y por lo tanto, seguiremos para que no se sigan vulnerando sus derechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ana Rosado pertenece al \u00c1rea de Migraciones de la APDHA Dice el art\u00edculo 13 DUDH que \u201cToda persona tiene derecho a circular libremente y a elegir su residencia en el territorio de un Estado. Toda persona tiene derecho a salir de cualquier pa\u00eds, incluso del propio, y a regresar a \u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.apdha.org\/cadiz\/derechos-humanos-en-la-frontera-sur\/\">Seguir Leyendo<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/derechos-humanos-en-la-frontera-sur\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" ><\/div><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fderechos-humanos-en-la-frontera-sur%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Derechos%20Humanos%20en%20la%20Frontera%20Sur&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fderechos-humanos-en-la-frontera-sur%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Derechos%20Humanos%20en%20la%20Frontera%20Sur https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fderechos-humanos-en-la-frontera-sur%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/derechos-humanos-en-la-frontera-sur\/\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fderechos-humanos-en-la-frontera-sur%2F&text=Derechos%20Humanos%20en%20la%20Frontera%20Sur\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div><div class='heateor_sss_sharing_container heateor_sss_vertical_sharing heateor_sss_bottom_sharing' style='width:37px;right: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3041'><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3041\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3041\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3041\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3041\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3041&text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>","protected":false},"author":1,"featured_media":3043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[346,16],"tags":[350],"_links":{"self":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3041"}],"collection":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/comments?post=3041"}],"version-history":[{"count":1,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3041\/revisions"}],"predecessor-version":[{"id":3044,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3041\/revisions\/3044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media\/3043"}],"wp:attachment":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media?parent=3041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/categories?post=3041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/tags?post=3041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}