{"id":3563,"date":"2019-08-20T10:22:17","date_gmt":"2019-08-20T10:22:17","guid":{"rendered":"https:\/\/www.apdha.org\/cadiz\/?p=3563"},"modified":"2019-08-20T10:22:17","modified_gmt":"2019-08-20T10:22:17","slug":"manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada","status":"publish","type":"post","link":"https:\/\/www.apdha.org\/cadiz\/manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada\/","title":{"rendered":"MANIFIESTO CONCENTRACI\u00d3N | No m\u00e1s abandono para la juventud extutelada"},"content":{"rendered":"<p>El martes 20 de agosto diversos colectivos de la provincia de C\u00e1diz nos concentramos en la Delegaci\u00f3n territorial de Igualdad, Pol\u00edticas Sociales y Conciliaci\u00f3n de la Junta de Andaluc\u00eda para denunciar el abandono institucional de los ex menores tutelados.\u00a0En la misma le\u00edmos el siguiente manifiesto:<\/p>\n<p><span style=\"color: #008080;\"><strong><u>MANIFIESTO POR LA DIGNIDAD Y LOS DERECHOS \u00a0<\/u><\/strong><strong><u>DE LAS PERSONAS J\u00d3VENES EXTUTELADAS<\/u><\/strong><\/span><\/p>\n<p>Las entidades abajo firmantes nos hacemos eco de la situaci\u00f3n en que se encuentran las personas j\u00f3venes procedentes del sistema de protecci\u00f3n de menores de la Junta de Andaluc\u00eda que, al cumplir la mayor\u00eda de edad,son abandonadas por la Administraci\u00f3n y, sin ning\u00fan tipo de recursos alternativos, se ven abocadas a una nueva situaci\u00f3n de desamparo, promovida, esta vez, por la propia Junta de Andaluc\u00eda. Ese desamparo se a\u00f1ade al que ya sufrieron en su d\u00eda, mientras eran menores de edad, y es ahoraparad\u00f3jicamente la misma Junta la que, de ser responsable de su protecci\u00f3n y tutela pasa a dejarlos en situaci\u00f3n de abandonoa su suerte, sin apoyo habitacional, sin recursos econ\u00f3micos, sin regularizar su documentaci\u00f3n.<\/p>\n<p>La transici\u00f3n de una situaci\u00f3n de protecci\u00f3n a una situaci\u00f3n de autonom\u00eda no se puede llevar de esta manera. Se trata de un camino \u00fanico y personal en que factores como la familia, el origen, los recursos disponibles y las propias capacidades juegan un papel decisivo. Es a la vez un proceso din\u00e1mico, que evoluciona a lo largo de la vida de la persona y que puede mejorar mediante un plan de acci\u00f3n.<\/p>\n<p>A partir de los 18 a\u00f1os, las personas j\u00f3venes que estaban tuteladas necesitan medidas de apoyo para poder pasar de una situaci\u00f3n de protecci\u00f3n a una de plena autonom\u00eda. Estas personas, que carecen de apoyo familiar, requieren de un acompa\u00f1amiento para que su proyecto de emancipaci\u00f3n sea un \u00e9xito y para que alcancen una situaci\u00f3n de madurez que les permita vivir plenamente una vida adulta e independiente.<\/p>\n<p>Sin embargo, desde la Administraci\u00f3n no existe plan alguno en ese sentido, de modo que estas personas j\u00f3venes quedan abocadas al vac\u00edo, expuestas a la m\u00e1s cruel vulnerabilidad y exclusi\u00f3n, de golpe y sin previo aviso.<\/p>\n<p>M\u00e1s de la mitad de laspersonas j\u00f3venes extuteladas depende de los apoyos de servicios sociales.<\/p>\n<p>Durante la minor\u00eda de edad se deber\u00edan abordar estrategias de preparaci\u00f3n para la vida adulta desde los Centros de Protecci\u00f3n, pero la ausencia de recursos y la mala planificaci\u00f3n inciden de forma contundente para\u00a0que los j\u00f3venes no salgan debidamente preparados de los recursos y se encuentren con un gran vac\u00edo en el tr\u00e1nsito a la vida adulta.<\/p>\n<p><strong>En estos d\u00edas hemos contemplado c\u00f3mo, de forma abrupta, se instruye a las direcciones de los centros de protecci\u00f3n de menores para que en cuesti\u00f3n de horas pongan en la calle a quienes cumplen 18 a\u00f1os, sin ning\u00fan recurso alternativo. En estos d\u00edas m\u00e1s de 10 j\u00f3venes en la provincia de C\u00e1diz, de distintas nacionalidades, han tenido que dormir con el cielo como techo; otros casos se han dado tambi\u00e9n en Almer\u00eda, en M\u00e1laga, en C\u00f3rdoba, en toda Andaluc\u00eda.<\/strong><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-3563 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apdha.org\/cadiz\/manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab\/'><img width=\"900\" height=\"675\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab-1024x768.jpg 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab-300x225.jpg 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab-768x576.jpg 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab-150x113.jpg 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2ed8cfcf-5d2f-472a-ae3f-fc72c0cb58ab.jpg 1599w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.apdha.org\/cadiz\/manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada\/5605e8cf-26f5-428e-9cd7-c0b54596f783\/'><img width=\"900\" height=\"675\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5605e8cf-26f5-428e-9cd7-c0b54596f783-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5605e8cf-26f5-428e-9cd7-c0b54596f783-1024x768.jpg 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5605e8cf-26f5-428e-9cd7-c0b54596f783-300x225.jpg 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5605e8cf-26f5-428e-9cd7-c0b54596f783-768x576.jpg 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5605e8cf-26f5-428e-9cd7-c0b54596f783-150x113.jpg 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5605e8cf-26f5-428e-9cd7-c0b54596f783.jpg 1599w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Hay que se\u00f1alar que este hecho no es nuevo, pero sigue atent\u00e1ndose contra los derechos humanos, contra la infancia y adolescencia m\u00e1s desprotegida, contra los principios de la democracia. Y no podemos callarnos ante una situaci\u00f3n tan grave.<\/p>\n<p>En estos \u00faltimos 20 a\u00f1os, la presencia de ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes menores de edad extranjeros ha significado una oportunidad para reformular la manera de gestionar la diversidad cultural en el \u00e1mbito de la infancia, as\u00ed como para profundizar en el acompa\u00f1amiento y la intervenci\u00f3n desde un trabajo interdisciplinar en red.<\/p>\n<p>La movilidad infantil y juvenil en este mundo globalizado no es un problema, sino una ventana de oportunidad para pensar y evaluar la calidad del estado de derecho.<\/p>\n<p>La Junta de Andaluc\u00eda debe cumplir con las responsabilidades contra\u00eddas en virtud de las normativas y directivas a nivel europeo, as\u00ed como con todas las dem\u00e1s normas internacionales relativas a los derechos de los menores, y en materia de protecci\u00f3n a la infancia y a la juventud.<\/p>\n<p>Por todo ello y ante la emergencia de los problemas que afrontan un n\u00famero importante de j\u00f3venes que han estado en centros de protecci\u00f3n recientemente,<\/p>\n<p>EXIGIMOS a la Administraci\u00f3n de la Consejer\u00eda de Igualdad, Pol\u00edticas Sociales y Conciliaci\u00f3n de la Junta de Andaluc\u00eda y al Gobierno de Espa\u00f1a:<\/p>\n<p>1.- El cese inmediato de todas las salidas de j\u00f3venes que han cumplido la mayor\u00eda de edad que se encuentren actualmente en centros de menores del sistema de protecci\u00f3n de la Junta de Andaluc\u00eda, hasta en tanto no se les asignen recursos alternativos de vivienda, alimentaci\u00f3n, formaci\u00f3n e inserci\u00f3n socio laboral.<\/p>\n<p>2.- El apoyo, con la puesta a disposici\u00f3n de recursos que garanticen la cobertura de las necesidades b\u00e1sicas, a todas aquellas personas j\u00f3venes procedentes del sistema de protecci\u00f3n que se encuentran en situaci\u00f3n de calle tras ser abandonadas a su suerte por la administraci\u00f3n.<\/p>\n<p>3.- El cambio inmediato en la Ley de la Infancia y Adolescencia en Andaluc\u00eda, de manera que se contemple la protecci\u00f3n a j\u00f3venes que se encuentren bajo la tutela o la guarda de la Junta de Andaluc\u00eda hasta los 26 a\u00f1os, poniendo a disposici\u00f3n presupuesto y\u00a0\u00a0alternativa de recursos de vivienda, itinerario educativo, apoyo en su situaci\u00f3n de salud f\u00edsica y mental, soporte jur\u00eddico, red de soporte social y medidas que propicien la inserci\u00f3n laboral.<\/p>\n<p>4.- Una reflexi\u00f3n por parte del Gobierno del Estado dirigida a dise\u00f1ar y poner en marcha un Plan Nacional sobre inmigraci\u00f3n infantil y juvenil. Entre los temas que urgen tratar, apuntamos a la necesidad de que se eliminen las barreras de inclusi\u00f3n de estas personas menores y j\u00f3venes extranjeras en el sistema educativo, se eviten las macro instituciones, con frecuencia en situaci\u00f3n de hacinamiento, se promocione su inserci\u00f3n laboral, y se les apoye en su transici\u00f3n a la vida adulta. En dicha reflexi\u00f3n hay que abandonar la estrategia de seguridad y de control fronterizo de las pol\u00edticas migratorias que dan lugar a que la titularidad de los derechos de ni\u00f1os y ni\u00f1as, adolescentes y j\u00f3venes sea constantemente puesta en duda por su doble condici\u00f3n de menores y extranjeros.<\/p>\n<p>5.- Que el Ministerio Fiscal vele por hacer prevalecer la protecci\u00f3n de la infancia y la adolescencia, haciendo cumplir la normativa y las sentencias de los tribunales nacionales e internacionales que ordenan la defensa y tutela de los derechos fundamentales de estos ni\u00f1os, ni\u00f1as y adolescentes menores de edad, asumiendo con firmeza las directrices del Comit\u00e9 de los Derechos del Ni\u00f1o.<\/p>\n<p><strong>Nuestra voluntad como sociedad civil es comprometernos a seguir denunciando los atropellos que se producen en los derechos fundamentales de esta poblaci\u00f3n tan vulnerable, por justicia, por equidad y por la defensa del desarrollo de los valores democr\u00e1ticos y de derecho<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes 20 de agosto diversos colectivos de la provincia de C\u00e1diz nos concentramos en la Delegaci\u00f3n territorial de Igualdad, Pol\u00edticas Sociales y Conciliaci\u00f3n de la Junta de Andaluc\u00eda para denunciar el abandono institucional de los ex menores tutelados.\u00a0En la misma le\u00edmos el siguiente manifiesto: MANIFIESTO POR LA DIGNIDAD Y \u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.apdha.org\/cadiz\/manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada\/\">Seguir Leyendo<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" ><\/div><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fmanifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=MANIFIESTO%20CONCENTRACI%C3%93N%20%7C%20No%20m%C3%A1s%20abandono%20para%20la%20juventud%20extutelada&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fmanifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=MANIFIESTO%20CONCENTRACI%C3%93N%20%7C%20No%20m%C3%A1s%20abandono%20para%20la%20juventud%20extutelada https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fmanifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/manifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada\/\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fmanifiesto-concentracion-no-mas-abandono-para-la-juventud-extutelada%2F&text=MANIFIESTO%20CONCENTRACI%C3%93N%20%7C%20No%20m%C3%A1s%20abandono%20para%20la%20juventud%20extutelada\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div><div class='heateor_sss_sharing_container heateor_sss_vertical_sharing heateor_sss_bottom_sharing' style='width:37px;right: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3563'><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3563\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3563\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3563\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3563\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F3563&text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>","protected":false},"author":1,"featured_media":3565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3563"}],"collection":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/comments?post=3563"}],"version-history":[{"count":2,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3563\/revisions"}],"predecessor-version":[{"id":3570,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/3563\/revisions\/3570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media\/3565"}],"wp:attachment":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media?parent=3563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/categories?post=3563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/tags?post=3563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}