{"id":6679,"date":"2024-01-29T08:21:30","date_gmt":"2024-01-29T08:21:30","guid":{"rendered":"https:\/\/www.apdha.org\/cadiz\/?p=6679"},"modified":"2024-01-29T08:21:30","modified_gmt":"2024-01-29T08:21:30","slug":"comunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024","status":"publish","type":"post","link":"https:\/\/www.apdha.org\/cadiz\/comunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024\/","title":{"rendered":"Comunicado por el D\u00eda Escolar de la No Violencia y La Paz 2024"},"content":{"rendered":"<div>\n<p class=\"LO-normal\"><i><strong>C\u00e1diz, 25 de enero de 2024.<\/strong> La circular de la Consejer\u00eda de Educaci\u00f3n sobre el DENYP ha impactado fuertemente en los centros andaluces por el componente de adoctrinamiento que conlleva. Sin ning\u00fan pudor se ha optado por priorizar la agenda pol\u00edtica, imponer sus valores y su posicionamiento a una comunidad educativa que no sale de su asombro.<\/i><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><i>No conseguir\u00e1n manipular a nuestra Escuela que vive, vivimos, inmersos en una actualidad b\u00e9lica marcada por la guerra en Ucrania y por el genocidio sobre la poblaci\u00f3n civil de Gaza.<\/i><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><i>Con el comunicado siguiente, las entidades firmantes instamos a reflexionar sobre la crueldad de la guerra, mucho m\u00e1s relevante que nunca en este DENYP, mucho m\u00e1s que el conflicto que supuso ETA, \u00a0felizmente resuelto hace m\u00e1s de diez a\u00f1os, precisamente por argumentos como el di\u00e1logo, la negociaci\u00f3n y el consenso. Herramientas de una cultura de Paz que el alumnado debe conocer y manejar, m\u00e1s necesarias que nunca tambi\u00e9n para conseguir la paz y un lugar digno para el pueblo palestino.<\/i><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><b>\u00a0<\/b><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\" align=\"center\"><b>COMUNICADO D\u00cdA ESCOLAR DE LA NO VIOLENCIA Y LA PAZ 2024<\/b><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><i>\u00a0<\/i><span style=\"font-family: Ubuntu;\">El D\u00eda Escolar de la No Violencia y la Paz -que se celebra el 30 de Enero- debiera servir cada a\u00f1o para reafirmar un compromiso de los centros educativos con una Cultura de Paz que es incompatible con el concepto de seguridad asociado a la militarizaci\u00f3n continua del planeta.\u00a0 Lo de \u201csi quieres la paz prep\u00e1rate para la guerra\u201d\u00a0\u00a0 es una falacia que solo beneficia al negocio de las armas. Despu\u00e9s de\u00a0 guerras recientes como la de Siria, Irak o Afganist\u00e1n, la situaci\u00f3n en esos pa\u00edses no ha mejorado, solo han tra\u00eddo muerte y destrucci\u00f3n.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Los intereses geopol\u00edticos, estrat\u00e9gicos, los recursos naturales y m\u00e1s recientemente el petr\u00f3leo est\u00e1n detr\u00e1s de la mayor\u00eda de ellas. Y es que para poder vender armas se necesitan guerras.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Los colectivos abajo firmantes defendemos un cambio de rumbo en las prioridades de inversi\u00f3n y llamamos a construir, para las generaciones presentes y futuras, un mundo m\u00e1s justo y sostenible, sin odios ni supremacismos donde la paz sea posible.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Quiz\u00e1s sea la guerra contra el cambio clim\u00e1tico la \u00fanica realmente necesaria.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Un mundo donde se haga realidad la Declaraci\u00f3n Universal de los Derechos Humanos y donde se haga frente a\u00a0 los intereses econ\u00f3micos de los pa\u00edses ricos, intereses que se esconden detr\u00e1s de las guerras y los conflictos b\u00e9licos, guerras por los recursos econ\u00f3micos del planeta, guerras por el control de los territorios y de los pueblos.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Es tambi\u00e9n un momento adecuado para el recuerdo de las guerras olvidadas, un recuerdo para los conflictos armados que no aparecen en los informativos, pero que ocasionan tambi\u00e9n miles de muertos, fundamentalmente en \u00c1frica.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Es un crimen contra el Derecho internacional Humanitario cualquier ataque a hospitales y centros educativos, as\u00ed como cualquier ataque contra poblaci\u00f3n civil indefensa, y en especial contra menores. Un ejemplo di\u00e1fano de todo esto es lo que est\u00e1 ocurriendo con el pueblo palestino.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">El ataque sobre civiles del 7 de octubre desencaden\u00f3 una espiral de violencia que ha llevado al gobierno de Israel a acabar con la vida de m\u00e1s de 25.000 personas, m\u00e1s de la mitad de ellas ni\u00f1os y ni\u00f1as. Los ataques han destruido viviendas, campos de refugiados, escuelas, hospitales y todo tipo de infraestructuras.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Pensamos que el uso de la violencia jam\u00e1s va a servir para resolver este conflicto. El llamamiento de la ONU y de otras organizaciones internacionales a una soluci\u00f3n dialogada no ha encontrado m\u00e1s que odio y m\u00e1s destrucci\u00f3n.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Sud\u00e1frica ha tomado la decisi\u00f3n hist\u00f3rica de denunciarlo ante la Corte Internacional de Justicia y la ciudadan\u00eda mundial est\u00e1 presionando para que nuestros pa\u00edses tambi\u00e9n se sumen a esta denuncia.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">Obras de arte como\u00a0 el \u201cGuernica\u201d de Picasso, convertido en un s\u00edmbolo universal contra el horror de las guerras, o la serie de grabados \u201cDesastres de la guerra\u201d de Goya, u otros recursos culturales, pueden servir de marco para\u00a0 propiciar durante esta jornada la reflexi\u00f3n y debate necesarios en las aulas.<\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><i>Imaginamos que habr\u00e1 centros que seguir\u00e1n las instrucciones que la Consejer\u00eda de Educaci\u00f3n impone a la comunidad educativa, pero tambi\u00e9n estamos convencidos que otros muchos priorizar\u00e1n el rechazo del genocidio televisado que estamos viviendo al otro lado del mediterr\u00e1neo.<\/i><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\">\n<\/div>\n<div>\n<p class=\"LO-normal\" align=\"center\"><b>ASOCIACI\u00d3N PRO DERECHOS HUMANOS DE ANDALUC\u00cdA &#8211; C\u00c1DIZ<\/b><b><\/b><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\" align=\"center\"><b>ECOLOGISTAS EN ACCI\u00d3N C\u00c1DIZ<\/b><b><\/b><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\" align=\"center\"><b>USTEA C\u00c1DIZ<\/b><b><\/b><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><img class=\"alignnone size-full wp-image-6680\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Captura-de-pantalla-2024-01-29-a-las-9.14.03.png\" alt=\"\" width=\"1458\" height=\"326\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Captura-de-pantalla-2024-01-29-a-las-9.14.03.png 1458w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Captura-de-pantalla-2024-01-29-a-las-9.14.03-300x67.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Captura-de-pantalla-2024-01-29-a-las-9.14.03-1024x229.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Captura-de-pantalla-2024-01-29-a-las-9.14.03-768x172.png 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/Captura-de-pantalla-2024-01-29-a-las-9.14.03-150x34.png 150w\" sizes=\"(max-width: 1458px) 100vw, 1458px\" \/><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><a href=\"https:\/\/eldiariodelaeducacion.com\/2024\/01\/07\/abordar-el-conflicto-israel-palestina-en-las-aulas\/\">https:\/\/eldiariodelaeducacion.com\/2024\/01\/07\/abordar-el-conflicto-israel-palestina-en-las-aulas\/<\/a><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><a href=\"https:\/\/www.asociacionredes.org\/blog\/2024\/01\/23\/una-circular-sectaria-y-adoctrinadora\/\">https:\/\/www.asociacionredes.org\/blog\/2024\/01\/23\/una-circular-sectaria-y-adoctrinadora\/<\/a><\/p>\n<\/div>\n<div>\n<p class=\"LO-normal\"><a href=\"https:\/\/www.eldiario.es\/andalucia\/en-abierto\/gobierno-andaluz-no-conseguira-silenciar-comunidad-educativa-frente-horror-gaza_132_10860847.html\">https:\/\/www.eldiario.es\/andalucia\/en-abierto\/gobierno-andaluz-no-conseguira-silenciar-comunidad-educativa-frente-horror-gaza_132_10860847.html<\/a><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e1diz, 25 de enero de 2024. La circular de la Consejer\u00eda de Educaci\u00f3n sobre el DENYP ha impactado fuertemente en los centros andaluces por el componente de adoctrinamiento que conlleva. Sin ning\u00fan pudor se ha optado por priorizar la agenda pol\u00edtica, imponer sus valores y su posicionamiento a una comunidad \u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.apdha.org\/cadiz\/comunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024\/\">Seguir Leyendo<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/comunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" ><\/div><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fcomunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Comunicado%20por%20el%20D%C3%ADa%20Escolar%20de%20la%20No%20Violencia%20y%20La%20Paz%202024&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fcomunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Comunicado%20por%20el%20D%C3%ADa%20Escolar%20de%20la%20No%20Violencia%20y%20La%20Paz%202024 https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fcomunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/comunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024\/\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fcomunicado-por-el-dia-escolar-de-la-no-violencia-y-la-paz-2024%2F&text=Comunicado%20por%20el%20D%C3%ADa%20Escolar%20de%20la%20No%20Violencia%20y%20La%20Paz%202024\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div><div class='heateor_sss_sharing_container heateor_sss_vertical_sharing heateor_sss_bottom_sharing' style='width:37px;right: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6679'><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6679\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6679\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6679\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6679\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6679&text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>","protected":false},"author":1,"featured_media":6681,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,293,284,295],"tags":[],"_links":{"self":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6679"}],"collection":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/comments?post=6679"}],"version-history":[{"count":1,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6679\/revisions"}],"predecessor-version":[{"id":6682,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6679\/revisions\/6682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media\/6681"}],"wp:attachment":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media?parent=6679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/categories?post=6679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/tags?post=6679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}