{"id":6787,"date":"2024-03-15T12:00:18","date_gmt":"2024-03-15T12:00:18","guid":{"rendered":"https:\/\/www.apdha.org\/cadiz\/?p=6787"},"modified":"2024-03-15T12:00:18","modified_gmt":"2024-03-15T12:00:18","slug":"solucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria","status":"publish","type":"post","link":"https:\/\/www.apdha.org\/cadiz\/solucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria\/","title":{"rendered":"\u00a1Soluci\u00f3n Albergue ya! &#8211; Nadie sin Hogar | El Puerto de Santa Maria"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: center;\"><strong><u>\u00a1Soluci\u00f3n Albergue ya! &#8211; Nadie sin Hogar<\/u><\/strong><\/p>\n<p style=\"font-weight: 400; text-align: center;\"><strong>APDHA reclama soluci\u00f3n para las personas del albergue y una actuaci\u00f3n decidida del Ayto. a favor de las personas sin hogar en El Puerto<\/strong><\/p>\n<p style=\"font-weight: 400;\">Hoy la Asociaci\u00f3n pro Derechos Humanos -APDHA- se ha reunido con las personas que a\u00fan contin\u00faan en el Albergue Municipal localizado en la calle Acuario de El Puerto y ha exigido una soluci\u00f3n inmediata a su situaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">La gesti\u00f3n del Albergue Municipal por el Ayuntamiento de El Puerto ha sido esperp\u00e9ntica y desde el primer momento con el objetivo de acabar con uno de los pocos recursos existentes en nuestra ciudad para atender a las personas m\u00e1s desfavorecidas.<\/p>\n<p style=\"font-weight: 400;\">Lo cierto es que en El Puerto existe, como se\u00f1alan lo propios ex-trabajadores de la disuelta asociaci\u00f3n ANYDES, \u201cuna poblaci\u00f3n cronificada en el sinhogarismo\u201d. Pero no se sabe nada sobre tal poblaci\u00f3n, mucho menos cuantas son, ya que el Ayuntamiento desde Asuntos Sociales carece de pol\u00edtica alguna destinada a resolver la situaci\u00f3n de estas personas, ni siquiera ha acometido, como se hace en otras localidades un censo de la misma.<\/p>\n<p style=\"font-weight: 400;\">S\u00ed conocemos de su situaci\u00f3n. Lo han denunciado las personas que trabajaban para ANYDES: \u201cpasa unas semanas en el albergue de C\u00e1diz, luego va al de jerez, San Fernando, El Puerto, intervalos en cajeros, portales\u2026 Para luego volver a empezar; ese eufemismo de <strong>\u00b4<\/strong>Recurso Habitacional<strong>`<\/strong> no es m\u00e1s que esto, un peregrinar de albergue en albergue con periodos a cielo abierto\u201d. Es un buen resumen de como asume su responsabilidad con las personas sin hogar y las personas con menos recursos de la ciudad este Ayuntamiento.<\/p>\n<p><img class=\"alignnone size-full wp-image-6790\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe.jpg 1600w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe-300x225.jpg 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe-1024x768.jpg 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe-768x576.jpg 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe-1536x1152.jpg 1536w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/b0b4a55d-bfdd-4a1d-acf6-13313f83d7fe-150x113.jpg 150w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"font-weight: 400;\">En diciembre hab\u00eda 24 personas, de las que s\u00f3lo permanecen 7. Del resto nada se sabe porque nada se ha explicado sobre su destino y atenci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">El Albergue alojaba una media de 29 personas al dia, a las que ANUDES ofrec\u00eda \u201cpensi\u00f3n completa, cuatro comidas, higiene personal, lavander\u00eda, ropero, administraci\u00f3n de medicaci\u00f3n, acompa\u00f1amientos a Atenci\u00f3n Primaria, Especialistas, Recursos en Drogodependencia, derivaciones a Recursos de Larga Estancia, gestiones burocr\u00e1ticas\u2026y todo ello con calidad y calidez\u201d.<\/p>\n<p style=\"font-weight: 400;\">Pero desde hace cinco a\u00f1os el Ayuntamiento ha dejado de dar seguridad y soporte a la labor de ANYDES, pagando tarde y mal, sin Convenio y con la inseguridad que ello supone para las personas usuarias, los trabajadores y la propia Asociaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">Como se sabe finalmente ANYDES ha tenido que disolverse, continuando un tiempo y sin ning\u00fan recurso municipal de forma voluntaria la atenci\u00f3n y apoyo un grupo de personas dirigido por Manoli Bautista que merece todo nuestro reconocimiento. Pero se llega hasta donde se llega ante el abandono municipal.<\/p>\n<p style=\"font-weight: 400;\">La realidad ha sido que no solo no hubo intenci\u00f3n de continuidad para la labor de ANYDES, sino un abandono absoluto del propio albergue, al que \u201cno se le ha asignado ning\u00fan tipo de recurso para su mantenimiento en 10 a\u00f1os de uso; con el congelador industrial averiado, la lavadora, la secadora, numerosas goteras y atasco\u2026\u201d<\/p>\n<p style=\"font-weight: 400;\">Finalmente lograron expulsar de una u otra forma (coacciones, promesas, utilizaci\u00f3n oportunista de situaciones personales\u2026) a 17 personas. Y las 7 personas restantes quieren ubicarlas en Jerez o Algeciras, utilizando todo tipo de presiones para ello, la presencia e intimidaci\u00f3n policial, las amenazas, la furgoneta en la puerta para el traslado, intentar impedir que entren, clausurar la cocina, no proporcionando alimentos, etc\u2026<\/p>\n<p><img class=\"alignnone size-full wp-image-6789\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2.jpg 1600w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2-300x169.jpg 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2-1024x576.jpg 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2-768x432.jpg 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2-1536x864.jpg 1536w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/d8f0e18d-484e-4a06-ba78-6e5b976df6d2-150x84.jpg 150w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"font-weight: 400;\">Hay que tener en cuenta la existencia de menores, incluso una chica con discapacidad y personas con graves lesiones producidas por accidente en el mismo albergue. No se puede carecer tener menos humanidad ni menos escr\u00fapulos desde la gesti\u00f3n municipal.<\/p>\n<p style=\"font-weight: 400;\">Ante todo, ello la APDHA ha reivindicado:<\/p>\n<ul>\n<li>Soluci\u00f3n inmediata para las personas que quedan en el albergue, pasando por alojamiento temporal y terminando con la asignaci\u00f3n de una vivienda social. No se puede echar a nadie de ning\u00fan sitio sin una alternativa habitacional justa y digna.<\/li>\n<li>Rehabilitar el albergue de forma urgente, habilitando los presupuestos extraordinarios necesarios para ello.<\/li>\n<li>Establecer un censo de personas sin hogar o con graves problemas de vivienda en nuestra ciudad. Censo que comprenda no s\u00f3lo cual es la poblaci\u00f3n afectada, sino tambi\u00e9n abarque sus necesidades y propuestas de soluci\u00f3n.<\/li>\n<li>Elaboraci\u00f3n de un protocolo de actuaci\u00f3n, actualmente inexistente, a trav\u00e9s de una mesa de seguimiento de colectivos y personas afectadas.<\/li>\n<li>Es preciso contemplar la posibilidad de crear un equipo de calle como ya existe en otras localidades de la Bah\u00eda<\/li>\n<li>Como reclam\u00f3 la APDHA en febrero, todo ello no se puede hacer sino desde la transparencia y la participaci\u00f3n ciudadana. Por lo que proponemos la creaci\u00f3n inmediata de una Mesa de Personas sin Hogar, con la participaci\u00f3n de los colectivos sociales, los partidos pol\u00edticos presentes en la corporaci\u00f3n y algunas Personas sin Hogar.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">Por una imprescindible pol\u00edtica de dignidad y justicia para las personas con problemas de hogar en nuestra ciudad de El Puerto, APDHA impulsar\u00e1 cuantas acciones considere necesarias. Asimismo, contactar\u00e1 con colectivos y partidos de la ciudad para formar un frente com\u00fan de movilizaci\u00f3n social.<\/p>\n<p>&#8212;<\/p>\n<p style=\"font-weight: 400;\">El Puerto Santa Mar\u00eda 15 de marzo de 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Soluci\u00f3n Albergue ya! &#8211; Nadie sin Hogar APDHA reclama soluci\u00f3n para las personas del albergue y una actuaci\u00f3n decidida del Ayto. a favor de las personas sin hogar en El Puerto Hoy la Asociaci\u00f3n pro Derechos Humanos -APDHA- se ha reunido con las personas que a\u00fan contin\u00faan en el Albergue \u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.apdha.org\/cadiz\/solucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria\/\">Seguir Leyendo<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/solucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" ><\/div><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fsolucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=%C2%A1Soluci%C3%B3n%20Albergue%20ya%21%20-%20Nadie%20sin%20Hogar%20%7C%20El%20Puerto%20de%20Santa%20Maria&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fsolucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=%C2%A1Soluci%C3%B3n%20Albergue%20ya%21%20-%20Nadie%20sin%20Hogar%20%7C%20El%20Puerto%20de%20Santa%20Maria https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fsolucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/solucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria\/\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fsolucion-albergue-ya-nadie-sin-hogar-el-puerto-de-santa-maria%2F&text=%C2%A1Soluci%C3%B3n%20Albergue%20ya%21%20-%20Nadie%20sin%20Hogar%20%7C%20El%20Puerto%20de%20Santa%20Maria\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div><div class='heateor_sss_sharing_container heateor_sss_vertical_sharing heateor_sss_bottom_sharing' style='width:37px;right: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6787'><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6787\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6787\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6787\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6787\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6787&text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>","protected":false},"author":1,"featured_media":6790,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[287,289],"tags":[],"_links":{"self":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6787"}],"collection":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/comments?post=6787"}],"version-history":[{"count":3,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6787\/revisions"}],"predecessor-version":[{"id":6793,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/6787\/revisions\/6793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media\/6790"}],"wp:attachment":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media?parent=6787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/categories?post=6787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/tags?post=6787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}