{"id":7087,"date":"2024-10-09T09:03:33","date_gmt":"2024-10-09T09:03:33","guid":{"rendered":"https:\/\/www.apdha.org\/cadiz\/?p=7087"},"modified":"2024-10-09T09:03:33","modified_gmt":"2024-10-09T09:03:33","slug":"la-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil","status":"publish","type":"post","link":"https:\/\/www.apdha.org\/cadiz\/la-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil\/","title":{"rendered":"La ciudad de C\u00e1diz tiene casi un 30% de riesgo de pobreza infantil"},"content":{"rendered":"<h3 style=\"font-weight: 400; text-align: center;\">Derechos Humanos denuncia que la ciudad de C\u00e1diz tiene casi un 30 por ciento de riesgo de pobreza infantil<\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><strong>*Descarga el informe aqu\u00ed: Estudio sobre la situaci\u00f3n socioecon\u00f3mica de la infancia en la ciudad de C\u00e1diz <a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/V2-ESTUDIO-SOBRE-LA-SITUACION-SOCIOECONOMICA-DE-LA-INFANCIA-EN-LA-CIUDAD-DE-CADIZ.-18-agosto-2024-2.pdf\" target=\"_blank\" rel=\"noopener\">Estudio sobre la situaci\u00f3n socioeconomica de la infancia en la ciudad de C\u00e1diz<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\"><strong>La entidad andaluza ha presentado, coincidiendo con el inicio del curso escolar, un extenso estudio realizado a lo largo del curso pasado en los centros de educaci\u00f3n infantil, primaria y secundaria de la ciudad.<\/strong><\/p>\n<p>Un total de 355 familias de la ciudad de C\u00e1diz han participado en el <strong><a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/V2-ESTUDIO-SOBRE-LA-SITUACION-SOCIOECONOMICA-DE-LA-INFANCIA-EN-LA-CIUDAD-DE-CADIZ.-18-agosto-2024-2.pdf\" target=\"_blank\" rel=\"noopener\">estudio elaborado por la Asociaci\u00f3n Pro Derechos Humanos de Andaluc\u00eda<\/a><\/strong> y los datos recabados no pueden ser m\u00e1s preocupantes. A trav\u00e9s de las encuestas elaboradas se ha contabilizado que casi un 30% de los ni\u00f1os y ni\u00f1as de la capital gaditana se encuentran en situaci\u00f3n de riesgo de pobreza infantil.<\/p>\n<p style=\"font-weight: 400;\">Desde la propia delegaci\u00f3n de la APDHA en C\u00e1diz explican que <strong><em>\u201ca pesar de la crudeza de los datos obtenidos, creemos que la realidad es a\u00fan peor y especialmente cruel para un colectivo tan vulnerable como es la infancia gaditana\u201d<\/em><\/strong>.<\/p>\n<p><img class=\"alignnone size-full wp-image-7147\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/IMG_0215.heic\" alt=\"\" \/><\/p>\n<p style=\"font-weight: 400;\"><strong>El <a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/V2-ESTUDIO-SOBRE-LA-SITUACION-SOCIOECONOMICA-DE-LA-INFANCIA-EN-LA-CIUDAD-DE-CADIZ.-18-agosto-2024-2.pdf\" target=\"_blank\" rel=\"noopener\">estudio<\/a> comienza delimitando el tipo de pobreza existente en una ciudad como la nuestra<\/strong>, una pobreza que va m\u00e1s all\u00e1 de la falta de recursos b\u00e1sicos para la supervivencia, tambi\u00e9n bastante visible en la ciudad. E<strong>s<\/strong> <strong>un mal multidimensional<\/strong><strong>,<\/strong>\u00a0abierto a muchas consideraciones. Adem\u00e1s de comida y vivienda, hay que tener en cuenta otros aspectos como el acceso a la informaci\u00f3n, la brecha digital o la pobreza energ\u00e9tica.<\/p>\n<p>Entre los datos m\u00e1s significativos que aporta el estudio realizado, encontramos:<\/p>\n<ul>\n<li>Aunque el 98% de las familias pueden hacer las tres comidas al d\u00eda, hay 1 de cada 10 \u00a0(2 de cada 10 en intramuros) que para poder hacerlo tienen que recurrir al banco de alimentos o a algunas de las asociaciones existentes en la ciudad.<\/li>\n<li>L\u00f3gicamente, el consumo de frutas y verduras, tan necesario en la infancia, no se puede realizar en muchas casas. Concretamente, en casi un 30 % de las familias del casco antiguo.<\/li>\n<li>Un 20% de las familias estudiadas reconocen ingresos por debajo de los 1000 euros al mes, cifra que se dispara hasta el 40% en intramuros.<\/li>\n<li>Tambi\u00e9n aqu\u00ed se llega hasta un 40 % en aquellas familias que dicen tener serias dificultades para asumir los gastos del material escolar o para responder econ\u00f3micamente a las propuestas de actividades que le solicitan desde el centro educativo.<\/li>\n<li>Pr\u00e1cticamente la mitad de las familias encuestadas dicen no poder mantener su hogar a la temperatura adecuada, al tener muchas dificultades para pagar el recibo de la luz.<\/li>\n<li>Aunque la mayor\u00eda de los hogares gaditanos tiene una conexi\u00f3n a internet, en muchos de ellos no se dispone de ordenador para realizar las tareas escolares.<\/li>\n<\/ul>\n<div id=\"attachment_7083\" style=\"width: 444px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/V2-ESTUDIO-SOBRE-LA-SITUACION-SOCIOECONOMICA-DE-LA-INFANCIA-EN-LA-CIUDAD-DE-CADIZ.-18-agosto-2024-2.pdf\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-7083\" class=\"wp-image-7083\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27.png\" alt=\"\" width=\"434\" height=\"614\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27.png 1587w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27-212x300.png 212w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27-724x1024.png 724w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27-768x1086.png 768w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27-1086x1536.png 1086w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27-1448x2048.png 1448w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-27-106x150.png 106w\" sizes=\"(max-width: 434px) 100vw, 434px\" \/><\/a><p id=\"caption-attachment-7083\" class=\"wp-caption-text\">Accede al estudio pinchando en la fotograf\u00eda<\/p><\/div>\n<p style=\"font-weight: 400;\">El <strong><a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/V2-ESTUDIO-SOBRE-LA-SITUACION-SOCIOECONOMICA-DE-LA-INFANCIA-EN-LA-CIUDAD-DE-CADIZ.-18-agosto-2024-2.pdf\" target=\"_blank\" rel=\"noopener\">estudio<\/a><\/strong> demuestra que el casco antiguo de la ciudad ser\u00eda la zona con mayor incidencia de pobreza infantil. APDHA denuncia que <em><strong>\u201cdetr\u00e1s de la ciudad tur\u00edstica y fotografiada diariamente por miles de visitantes, hay familias que viven por debajo del umbral de la dignidad\u201d<\/strong><\/em>. Pro Derechos Humanos de Andaluc\u00eda ha constatado la presencia de alumnos y alumnas con pautas alimenticias deficitarias o poco saludables, hogares donde el paro y\/o el empleo precario hacen que se llegue con muchas dificultades a fin de mes, y que cualquier gasto extra resulte imposible.\u00a0 <strong><em>\u201cSe trata de hogares donde la pobreza energ\u00e9tica y la brecha digital son una realidad\u201d<\/em><\/strong>, explican desde APDHA C\u00e1diz.<\/p>\n<p style=\"font-weight: 400;\"><em><strong>\u201cNos parece muy dif\u00edcil de digerir que una sociedad como la gaditana, en pleno siglo XXI, pueda asumir una realidad tan demoledora como \u00e9sta. Y m\u00e1s en una sociedad tan envejecida como la nuestra, donde el n\u00famero de mascotas supera ampliamente desde hace a\u00f1os el de ni\u00f1os\u201d<\/strong><\/em>, aseguran desde la entidad. <em><strong>\u201cLos ni\u00f1os y ni\u00f1as de C\u00e1diz, que deber\u00edan ser considerados como un tesoro a cuidar, no tienen garantizados sus derechos m\u00e1s esenciales\u201d<\/strong><\/em>, explica la entidad andaluza.<\/p>\n<p style=\"font-weight: 400;\">El informe finaliza recogiendo un <strong><a href=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/V2-ESTUDIO-SOBRE-LA-SITUACION-SOCIOECONOMICA-DE-LA-INFANCIA-EN-LA-CIUDAD-DE-CADIZ.-18-agosto-2024-2.pdf\" target=\"_blank\" rel=\"noopener\">listado de propuestas<\/a><\/strong> ya realizadas por diversas entidades con medidas concretas para dar respuesta a esta realidad, y que aun se encuentran pendientes de implementar.<\/p>\n<p style=\"font-weight: 400;\">La APDHA hace un llamamiento a las administraciones (estatal, auton\u00f3mica y local) para que implementen de manera urgente medidas para paliar este drama. Nos encontramos ante un problema social muy grave, la pobreza afecta de manera negativa al bienestar y desarrollo de la infancia. Adem\u00e1s, lastra el talento y el potencial de la sociedad, se trata de un\u00a0<strong>problema estructural y una vulneraci\u00f3n de derechos<\/strong>\u00a0que, desgraciadamente, se est\u00e1 normalizando. Y lo m\u00e1s preocupante es que si no se act\u00faa, los efectos de esta pobreza permanecen en el tiempo y, en 4 de cada 5 casos, se transmiten de generaci\u00f3n en generaci\u00f3n. Es decir, la pobreza, al igual que la riqueza, tambi\u00e9n se hereda.<\/p>\n<p style=\"font-weight: 400;\">La apertura del nuevo curso escolar no puede obviar esta realidad. <strong>\u201cNo es justo\u201d<\/strong>, sentencian desde la APDHA.<\/p>\n<hr \/>\n<p>El informe en posts:<\/p>\n<p><img class=\"alignnone wp-image-7090\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-28.png\" alt=\"\" width=\"398\" height=\"398\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-28.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-28-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-28-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-28-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-28-768x768.png 768w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/> <img class=\"alignnone wp-image-7091\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-24.png\" alt=\"\" width=\"393\" height=\"393\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-24.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-24-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-24-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-24-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-24-768x768.png 768w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/> <img class=\"alignnone size-full wp-image-7092\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-16.png\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-16.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-16-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-16-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-16-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-16-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/> <img class=\"alignnone wp-image-7093\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-17.png\" alt=\"\" width=\"397\" height=\"397\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-17.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-17-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-17-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-17-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-17-768x768.png 768w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/> <img class=\"alignnone wp-image-7094\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-14.png\" alt=\"\" width=\"397\" height=\"397\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-14.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-14-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-14-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-14-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-14-768x768.png 768w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/> <img class=\"alignnone size-full wp-image-7095\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-14.png\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-14.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-14-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-14-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-14-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-14-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/> <img class=\"alignnone wp-image-7096\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-13.png\" alt=\"\" width=\"396\" height=\"396\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-13.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-13-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-13-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-13-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-13-768x768.png 768w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/> <img class=\"alignnone wp-image-7097\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-11.png\" alt=\"\" width=\"395\" height=\"395\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-11.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-11-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-11-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-11-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-11-768x768.png 768w\" sizes=\"(max-width: 395px) 100vw, 395px\" \/> <img class=\"alignnone wp-image-7098\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-6.png\" alt=\"\" width=\"394\" height=\"394\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-6.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-6-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-6-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-6-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-6-768x768.png 768w\" sizes=\"(max-width: 394px) 100vw, 394px\" \/> <img class=\"alignnone wp-image-7099\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-3.png\" alt=\"\" width=\"396\" height=\"396\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-3.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-3-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-3-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-3-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-3-768x768.png 768w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img class=\"alignnone size-full wp-image-7101\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-29.png\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-29.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-29-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-29-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-29-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/1-29-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/> <img class=\"alignnone wp-image-7102\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-25.png\" alt=\"\" width=\"396\" height=\"396\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-25.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-25-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-25-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-25-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/2-25-768x768.png 768w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/> <img class=\"alignnone wp-image-7103\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-17.png\" alt=\"\" width=\"395\" height=\"395\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-17.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-17-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-17-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-17-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/3-17-768x768.png 768w\" sizes=\"(max-width: 395px) 100vw, 395px\" \/> <img class=\"alignnone size-full wp-image-7104\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-18.png\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-18.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-18-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-18-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-18-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/4-18-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/> <img class=\"alignnone wp-image-7105\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-15.png\" alt=\"\" width=\"396\" height=\"396\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-15.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-15-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-15-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-15-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/5-15-768x768.png 768w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/> <img class=\"alignnone wp-image-7106\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-15.png\" alt=\"\" width=\"397\" height=\"397\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-15.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-15-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-15-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-15-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/6-15-768x768.png 768w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/> <img class=\"alignnone size-full wp-image-7107\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-14.png\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-14.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-14-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-14-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-14-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/7-14-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/> <img class=\"alignnone wp-image-7108\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-12.png\" alt=\"\" width=\"394\" height=\"394\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-12.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-12-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-12-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-12-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/8-12-768x768.png 768w\" sizes=\"(max-width: 394px) 100vw, 394px\" \/> <img class=\"alignnone wp-image-7109\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-7.png\" alt=\"\" width=\"395\" height=\"395\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-7.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-7-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-7-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-7-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/9-7-768x768.png 768w\" sizes=\"(max-width: 395px) 100vw, 395px\" \/> <img class=\"alignnone size-full wp-image-7110\" src=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-4.png\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-4.png 1080w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-4-300x300.png 300w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-4-1024x1024.png 1024w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-4-150x150.png 150w, https:\/\/www.apdha.org\/cadiz\/wp-content\/uploads\/10-4-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derechos Humanos denuncia que la ciudad de C\u00e1diz tiene casi un 30 por ciento de riesgo de pobreza infantil &nbsp; *Descarga el informe aqu\u00ed: Estudio sobre la situaci\u00f3n socioecon\u00f3mica de la infancia en la ciudad de C\u00e1diz Estudio sobre la situaci\u00f3n socioeconomica de la infancia en la ciudad de C\u00e1diz \u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.apdha.org\/cadiz\/la-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil\/\">Seguir Leyendo<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/la-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" ><\/div><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fla-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=La%20ciudad%20de%20C%C3%A1diz%20tiene%20casi%20un%2030%25%20de%20riesgo%20de%20pobreza%20infantil&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fla-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=La%20ciudad%20de%20C%C3%A1diz%20tiene%20casi%20un%2030%25%20de%20riesgo%20de%20pobreza%20infantil https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fla-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/la-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil\/\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fla-ciudad-de-cadiz-tiene-casi-un-30-de-riesgo-de-pobreza-infantil%2F&text=La%20ciudad%20de%20C%C3%A1diz%20tiene%20casi%20un%2030%25%20de%20riesgo%20de%20pobreza%20infantil\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:35px;height:35px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div><div class='heateor_sss_sharing_container heateor_sss_vertical_sharing heateor_sss_bottom_sharing' style='width:37px;right: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-heateor-sss-href='https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/7087'><div class=\"heateor_sss_sharing_ul\"><a class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7087\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#3c589a;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_twitter\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz&url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7087\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7087\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"heateor_sss_button_copy_link\" title=\"Copy Link\" rel=\"nofollow noopener\" href=\"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/7087\" onclick=\"event.preventDefault()\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_copy_link\" style=\"background-color:#ffc112;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 40 40\"><path fill=\"#fff\" d=\"M24.412 21.177c0-.36-.126-.665-.377-.917l-2.804-2.804a1.235 1.235 0 0 0-.913-.378c-.377 0-.7.144-.97.43.026.028.11.11.255.25.144.14.24.236.29.29s.117.14.2.256c.087.117.146.232.177.344.03.112.046.236.046.37 0 .36-.126.666-.377.918a1.25 1.25 0 0 1-.918.377 1.4 1.4 0 0 1-.373-.047 1.062 1.062 0 0 1-.345-.175 2.268 2.268 0 0 1-.256-.2 6.815 6.815 0 0 1-.29-.29c-.14-.142-.223-.23-.25-.254-.297.28-.445.607-.445.984 0 .36.126.664.377.916l2.778 2.79c.243.243.548.364.917.364.36 0 .665-.118.917-.35l1.982-1.97c.252-.25.378-.55.378-.9zm-9.477-9.504c0-.36-.126-.665-.377-.917l-2.777-2.79a1.235 1.235 0 0 0-.913-.378c-.35 0-.656.12-.917.364L7.967 9.92c-.254.252-.38.553-.38.903 0 .36.126.665.38.917l2.802 2.804c.242.243.547.364.916.364.377 0 .7-.14.97-.418-.026-.027-.11-.11-.255-.25s-.24-.235-.29-.29a2.675 2.675 0 0 1-.2-.255 1.052 1.052 0 0 1-.176-.344 1.396 1.396 0 0 1-.047-.37c0-.36.126-.662.377-.914.252-.252.557-.377.917-.377.136 0 .26.015.37.046.114.03.23.09.346.175.117.085.202.153.256.2.054.05.15.148.29.29.14.146.222.23.25.258.294-.278.442-.606.442-.983zM27 21.177c0 1.078-.382 1.99-1.146 2.736l-1.982 1.968c-.745.75-1.658 1.12-2.736 1.12-1.087 0-2.004-.38-2.75-1.143l-2.777-2.79c-.75-.747-1.12-1.66-1.12-2.737 0-1.106.392-2.046 1.183-2.818l-1.186-1.185c-.774.79-1.708 1.186-2.805 1.186-1.078 0-1.995-.376-2.75-1.13l-2.803-2.81C5.377 12.82 5 11.903 5 10.826c0-1.08.382-1.993 1.146-2.738L8.128 6.12C8.873 5.372 9.785 5 10.864 5c1.087 0 2.004.382 2.75 1.146l2.777 2.79c.75.747 1.12 1.66 1.12 2.737 0 1.105-.392 2.045-1.183 2.817l1.186 1.186c.774-.79 1.708-1.186 2.805-1.186 1.078 0 1.995.377 2.75 1.132l2.804 2.804c.754.755 1.13 1.672 1.13 2.75z\"\/><\/svg><\/span><\/a><a class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a class=\"heateor_sss_button_telegram\" href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fwww.apdha.org%2Fcadiz%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7087&text=Asociaci%C3%B3n%20Pro%20Derechos%20Humanos%20de%20Andaluc%C3%ADa%20-%20APDHA%20Delegaci%C3%B3n%20de%20C%C3%A1diz\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_telegram\" style=\"background-color:#3da5f1;width:33px;height:33px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M25.515 6.896L6.027 14.41c-1.33.534-1.322 1.276-.243 1.606l5 1.56 1.72 5.66c.226.625.115.873.77.873.506 0 .73-.235 1.012-.51l2.43-2.363 5.056 3.734c.93.514 1.602.25 1.834-.863l3.32-15.638c.338-1.363-.52-1.98-1.41-1.577z\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>","protected":false},"author":1,"featured_media":7083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,287,291],"tags":[],"_links":{"self":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/7087"}],"collection":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/comments?post=7087"}],"version-history":[{"count":9,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/7087\/revisions"}],"predecessor-version":[{"id":7148,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/posts\/7087\/revisions\/7148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media\/7083"}],"wp:attachment":[{"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/media?parent=7087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/categories?post=7087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apdha.org\/cadiz\/wp-json\/wp\/v2\/tags?post=7087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}